{"id":7,"count":19,"description":"<h2 class=\"p1\"><b>Servicios laborales empresariales:<\/b><b><\/b><\/h2>\r\n<ol>\r\n \t<li>Contratos Individuales de Trabajo<\/li>\r\n \t<li>Reglamento Interior de Trabajo<\/li>\r\n \t<li><strong>Migratorio:<\/strong> registro de Garante, residencia de trabajador migrante y permiso de trabajo.<\/li>\r\n \t<li>Asistencia y representaci\u00f3n ante la Inspecci\u00f3n General de Trabajo y Juzgados de Trabajo<\/li>\r\n \t<li>Defensa Procesal en materia Laboral, mediante la interposici\u00f3n de Demandas Laborales y la implementaci\u00f3n de estrategias legales s\u00f3lidas.<\/li>\r\n \t<li>Negociaciones, conciliaciones y elaboraci\u00f3n de convenios y finiquitos.<\/li>\r\n \t<li>Creaci\u00f3n e implementaci\u00f3n de Estrategias de Prevenci\u00f3n en materia Laboral.<\/li>\r\n \t<li>Implementaci\u00f3n de figuras y Medidas de Higiene y Seguridad Ocupacional.<\/li>\r\n \t<li>Auditor\u00edas laborales exhaustivas para identificar posibles riesgos legales y asegurar el cumplimiento normativo.<\/li>\r\n \t<li>Asesoramiento, actualizaci\u00f3n y regularizaci\u00f3n de obligaciones patronales y laborales, para evitar sanciones y conflictos legales.<\/li>\r\n \t<li>Consultas especializadas en c\u00e1lculo y pago de prestaciones laborales, tales como vacaciones, indemnizaciones y dem\u00e1s prestaciones de ley.<\/li>\r\n \t<li>Asistencia y acompa\u00f1amiento en despidos y otras formas de terminaci\u00f3n de relaci\u00f3n laboral.<\/li>\r\n \t<li>Capacitaci\u00f3n a Gerentes, Directores y Contadores en materia Laboral, para asegurar un correcto manejo de los aspectos legales relacionados con el personal.<\/li>\r\n<\/ol>\r\n<strong><a href=\"https:\/\/www.conservisabogados.com\/en\/\">\u2190Acerca de Conservis Abogados<\/a><\/strong>\r\n<div class=\"host-bincmiainjofjnhchmcalkanjebghoen\" style=\"position: relative;z-index: 2147483647\"><\/div>\r\n<div class=\"simg-pop-btn\" style=\"top: 20px;left: 14px\"><\/div>\r\n<div class=\"host-bincmiainjofjnhchmcalkanjebghoen\" style=\"position: relative;z-index: 2147483647\"><\/div>\r\n<div class=\"host-bincmiainjofjnhchmcalkanjebghoen\" style=\"position: relative;z-index: 2147483647\"><\/div>\r\n<div class=\"simg-pop-btn\" style=\"top: 20px;left: 14px\"><\/div>\r\n<div class=\"host-bincmiainjofjnhchmcalkanjebghoen\" style=\"position: relative;z-index: 2147483647\"><\/div>\r\n<div class=\"simg-pop-btn\" style=\"top: 25px;left: 14px\" data-hover=\"0\"><\/div>\r\n<div class=\"host-bincmiainjofjnhchmcalkanjebghoen\" style=\"position: relative;z-index: 2147483647\"><\/div>\r\n<div class=\"host-bincmiainjofjnhchmcalkanjebghoen\" style=\"position: relative;z-index: 2147483647\"><\/div>\r\n<div class=\"simg-pop-btn\" style=\"top: 20px;left: 14px\"><\/div>\r\n<div class=\"host-bincmiainjofjnhchmcalkanjebghoen\" style=\"position: relative;z-index: 2147483647\"><\/div>\r\n<div class=\"simg-pop-btn\" style=\"top: 20px;left: 14px\"><\/div>\r\n<div class=\"simg-pop-btn\" style=\"top: 20px;left: 14px\"><\/div>\r\n<div class=\"host-bincmiainjofjnhchmcalkanjebghoen\" style=\"position: relative;z-index: 2147483647\"><\/div>\r\n<div class=\"simg-pop-btn\" style=\"top: 20px;left: 14px\"><\/div>","link":"https:\/\/www.conservisabogados.com\/en\/category\/derecho-laboral\/","name":"Abogados Laborales en Guatemala","slug":"derecho-laboral","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Abogados Laborales en Guatemala - CONSERVIS ABOGADOS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.conservisabogados.com\/en\/category\/derecho-laboral\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abogados Laborales en Guatemala - CONSERVIS ABOGADOS\" \/>\n<meta property=\"og:description\" content=\"Servicios laborales empresariales: Contratos Individuales de Trabajo Reglamento Interior de Trabajo Migratorio: registro de Garante, residencia de trabajador migrante y permiso de trabajo. Asistencia y representaci\u00f3n ante la Inspecci\u00f3n General de Trabajo y Juzgados de Trabajo Defensa Procesal en materia Laboral, mediante la interposici\u00f3n de Demandas Laborales y la implementaci\u00f3n de estrategias legales s\u00f3lidas. Negociaciones, conciliaciones y elaboraci\u00f3n de convenios y finiquitos. Creaci\u00f3n e implementaci\u00f3n de Estrategias de Prevenci\u00f3n en materia Laboral. Implementaci\u00f3n de figuras y Medidas de Higiene y Seguridad Ocupacional. Auditor\u00edas laborales exhaustivas para identificar posibles riesgos legales y asegurar el cumplimiento normativo. Asesoramiento, actualizaci\u00f3n y regularizaci\u00f3n de obligaciones patronales y laborales, para evitar sanciones y conflictos legales. Consultas especializadas en c\u00e1lculo y pago de prestaciones laborales, tales como vacaciones, indemnizaciones y dem\u00e1s prestaciones de ley. Asistencia y acompa\u00f1amiento en despidos y otras formas de terminaci\u00f3n de relaci\u00f3n laboral. Capacitaci\u00f3n a Gerentes, Directores y Contadores en materia Laboral, para asegurar un correcto manejo de los aspectos legales relacionados con el personal. \u2190Acerca de Conservis Abogados\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.conservisabogados.com\/en\/category\/derecho-laboral\/\" \/>\n<meta property=\"og:site_name\" content=\"CONSERVIS ABOGADOS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.conservisabogados.com\/category\/derecho-laboral\/\",\"url\":\"https:\/\/www.conservisabogados.com\/category\/derecho-laboral\/\",\"name\":\"Abogados Laborales en Guatemala - CONSERVIS ABOGADOS\",\"isPartOf\":{\"@id\":\"https:\/\/www.conservisabogados.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.conservisabogados.com\/category\/derecho-laboral\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.conservisabogados.com\/category\/derecho-laboral\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.conservisabogados.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abogados Laborales en Guatemala\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.conservisabogados.com\/#website\",\"url\":\"https:\/\/www.conservisabogados.com\/\",\"name\":\"CONSERVIS ABOGADOS\",\"description\":\"Bufete de Abogados en Guatemala\",\"publisher\":{\"@id\":\"https:\/\/www.conservisabogados.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.conservisabogados.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.conservisabogados.com\/#organization\",\"name\":\"CONSERVIS ABOGADOS\",\"url\":\"https:\/\/www.conservisabogados.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.conservisabogados.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.conservisabogados.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Conservis-Abogados-Bufete-de-Abogados-en-Guatemala-1.png\",\"contentUrl\":\"https:\/\/www.conservisabogados.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Conservis-Abogados-Bufete-de-Abogados-en-Guatemala-1.png\",\"width\":498,\"height\":500,\"caption\":\"CONSERVIS ABOGADOS\"},\"image\":{\"@id\":\"https:\/\/www.conservisabogados.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abogados Laborales en Guatemala - CONSERVIS ABOGADOS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.conservisabogados.com\/en\/category\/derecho-laboral\/","og_locale":"en_US","og_type":"article","og_title":"Abogados Laborales en Guatemala - CONSERVIS ABOGADOS","og_description":"Servicios laborales empresariales: Contratos Individuales de Trabajo Reglamento Interior de Trabajo Migratorio: registro de Garante, residencia de trabajador migrante y permiso de trabajo. Asistencia y representaci\u00f3n ante la Inspecci\u00f3n General de Trabajo y Juzgados de Trabajo Defensa Procesal en materia Laboral, mediante la interposici\u00f3n de Demandas Laborales y la implementaci\u00f3n de estrategias legales s\u00f3lidas. Negociaciones, conciliaciones y elaboraci\u00f3n de convenios y finiquitos. Creaci\u00f3n e implementaci\u00f3n de Estrategias de Prevenci\u00f3n en materia Laboral. Implementaci\u00f3n de figuras y Medidas de Higiene y Seguridad Ocupacional. Auditor\u00edas laborales exhaustivas para identificar posibles riesgos legales y asegurar el cumplimiento normativo. Asesoramiento, actualizaci\u00f3n y regularizaci\u00f3n de obligaciones patronales y laborales, para evitar sanciones y conflictos legales. Consultas especializadas en c\u00e1lculo y pago de prestaciones laborales, tales como vacaciones, indemnizaciones y dem\u00e1s prestaciones de ley. Asistencia y acompa\u00f1amiento en despidos y otras formas de terminaci\u00f3n de relaci\u00f3n laboral. Capacitaci\u00f3n a Gerentes, Directores y Contadores en materia Laboral, para asegurar un correcto manejo de los aspectos legales relacionados con el personal. \u2190Acerca de Conservis Abogados","og_url":"https:\/\/www.conservisabogados.com\/en\/category\/derecho-laboral\/","og_site_name":"CONSERVIS ABOGADOS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.conservisabogados.com\/category\/derecho-laboral\/","url":"https:\/\/www.conservisabogados.com\/category\/derecho-laboral\/","name":"Abogados Laborales en Guatemala - CONSERVIS ABOGADOS","isPartOf":{"@id":"https:\/\/www.conservisabogados.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.conservisabogados.com\/category\/derecho-laboral\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.conservisabogados.com\/category\/derecho-laboral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.conservisabogados.com\/"},{"@type":"ListItem","position":2,"name":"Abogados Laborales en Guatemala"}]},{"@type":"WebSite","@id":"https:\/\/www.conservisabogados.com\/#website","url":"https:\/\/www.conservisabogados.com\/","name":"CONSERVIS ABOGADOS","description":"Law Firm in Guatemala","publisher":{"@id":"https:\/\/www.conservisabogados.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.conservisabogados.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.conservisabogados.com\/#organization","name":"CONSERVIS ABOGADOS","url":"https:\/\/www.conservisabogados.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.conservisabogados.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.conservisabogados.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Conservis-Abogados-Bufete-de-Abogados-en-Guatemala-1.png","contentUrl":"https:\/\/www.conservisabogados.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Conservis-Abogados-Bufete-de-Abogados-en-Guatemala-1.png","width":498,"height":500,"caption":"CONSERVIS ABOGADOS"},"image":{"@id":"https:\/\/www.conservisabogados.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.conservisabogados.com\/en\/wp-json\/wp\/v2\/categories\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.conservisabogados.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.conservisabogados.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.conservisabogados.com\/en\/wp-json\/wp\/v2\/posts?categories=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}