{"id":4627,"date":"2022-02-25T16:19:48","date_gmt":"2022-02-25T16:19:48","guid":{"rendered":"https:\/\/conservisabogados.com\/?p=4627"},"modified":"2026-03-02T10:36:44","modified_gmt":"2026-03-02T16:36:44","slug":"matrimonio-en-guatemala-con-extranjero","status":"publish","type":"post","link":"https:\/\/www.conservisabogados.com\/en\/matrimonio-en-guatemala-con-extranjero\/","title":{"rendered":"Matrimonio en Guatemala Con Extranjero"},"content":{"rendered":"<p>Es posible que exista la oportunidad en alg\u00fan momento de contraer matrimonio con una persona extranjera y celebrarse en territorio guatemalteco.<\/p>\n<p>Nuestra legislaci\u00f3n, espec\u00edficamente el C\u00f3digo Civil, establece que el matrimonio es una instituci\u00f3n social por la que un hombre y una mujer se unen legalmente, con \u00e1nimo de permanencia y con el fin de vivir juntos, procrear, alimentar, educar a los hijos y auxiliarse entre s\u00ed.<\/p>\n<p>El matrimonio debe ser autorizado por un <a href=\"https:\/\/www.conservisabogados.com\/en\/\">Notario guatemalteco<\/a> y se deben cumplir los mismos requisitos requeridos como en el caso de dos contrayentes guatemaltecos. Pero adem\u00e1s de estos, es necesario tomar en cuenta ciertos procedimientos y requisitos especiales, los cuales explicamos y detallamos a continuaci\u00f3n para iniciar el proceso.<\/p>\n<h2><\/h2>\n<h2><strong>RECOLECCION DE DOCUMENTOS DE LOS CONTRAYENTES<\/strong><\/h2>\n<p>Para poder iniciar el proceso de celebraci\u00f3n del matrimonio es necesario obtener ciertos documentos personales de cada uno de los contrayentes:<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u00a0 \u00a0 A) DEL CONTRAYENTE NACIONAL<\/strong><\/h3>\n<ul>\n<li>Certificado de nacimiento, extendido por el RENAP.<\/li>\n<li>Documento Personal de Identificaci\u00f3n<\/li>\n<li>Certificado m\u00e9dico en el que conste que la persona no padece de enfermedad contagiosa incurable perjudicial al otro c\u00f3nyuge o a la descendencia o que no tiene defectos f\u00edsicos que imposibiliten la procreaci\u00f3n.<\/li>\n<li>Si fuese viudo o divorciado, deber constar dicha circunstancia en su certificaci\u00f3n de nacimiento.<\/li>\n<li>Nombres de los padres y de los abuelos si los supieren.<\/li>\n<li>Testigos propuestos.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3><strong>\u00a0 \u00a0 \u00a0B)DEL CONTRAYENTE EXTRANJERO<\/strong><\/h3>\n<ul>\n<li>Certificaci\u00f3n de nacimiento y Certificaci\u00f3n de solter\u00eda<\/li>\n<\/ul>\n<p>Ambos emitidos por el registro civil del pa\u00eds de origen de extranjero y deben encontrarse debidamente apostillados. Si dichos documentos se encuentran en idioma distinto al espa\u00f1ol, deber\u00e1n contar con su debida traducci\u00f3n jurada.<\/p>\n<ul>\n<li>Certificado m\u00e9dico en el que conste que la persona no padece de enfermedad contagiosa incurable perjudicial al otro c\u00f3nyuge o a la descendencia o que no tiene defectos f\u00edsicos que imposibiliten la procreaci\u00f3n.<\/li>\n<li>Pasaporte vigente<\/li>\n<li>Nombres de los padres y de los abuelos si los supieren.<\/li>\n<li>Testigos propuestos.<\/li>\n<li>Publicaciones de edictos en el diario oficial y otro de mayor circulaci\u00f3n por un plazo de 15 d\u00edas.<\/li>\n<li>Celebrar capitulaciones matrimoniales con un notario guatemalteco.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3><strong>CAPITULACIONES MATRIMONIALES<\/strong><\/h3>\n<p>Las capitulaciones matrimoniales son obligatorias al contraer matrimonio la mujer con un extranjero y de acuerdo a nuestra legislaci\u00f3n, son pactos que se otorgan entre los contrayentes con el fin de establecer y regular el r\u00e9gimen econ\u00f3mico del matrimonio.<\/p>\n<p>Estas deben celebrarse ante <a href=\"https:\/\/www.conservisabogados.com\/en\/\">Notario guatemalteco<\/a> y en escritura p\u00fablica, y deber\u00e1n comprender la designaci\u00f3n detallada que tenga cada uno de los c\u00f3nyuges al contraer matrimonio; declaraci\u00f3n del monto de las deudas personales, y la declaraci\u00f3n expresa su adoptar\u00e1n el r\u00e9gimen de comunidad de gananciales, separaci\u00f3n absoluta o la comunidad absoluta.<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>\n<h3><strong>REGIMEN DE COMUNIDAD DE GANANCIALES<\/strong><\/h3>\n<\/li>\n<\/ol>\n<p>Es el m\u00e1s com\u00fan en Guatemala, y es en el cual cada c\u00f3nyuge pone en com\u00fan y divide por partes iguales los beneficios obtenidos durante la vida en com\u00fan y, por lo tanto, una vez se produzca la separaci\u00f3n se repartir\u00e1 a la mitad entre ambos.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"2\">\n<li>\n<h3><strong>REGIMEN DE SEPARACION ABSOLUTA<\/strong><\/h3>\n<\/li>\n<\/ol>\n<p>Consiste en la separaci\u00f3n del patrimonio de cada c\u00f3nyuge, por lo tanto, las deudas contra\u00eddas por uno de ellos responden el patrimonio individual de cada uno.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<ol start=\"3\">\n<li>\n<h3><strong>REGIMEN DE COMUNIDAD ABSOLUTA<\/strong><\/h3>\n<\/li>\n<\/ol>\n<p>En el r\u00e9gimen de comunidad absoluta, todos los bienes aportados al matrimonio por los contrayentes o adquiridos durante el mismo, pertenecen al patrimonio conyugal y se dividir\u00e1n por mitad al disolverse el matrimonio.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Es posible que exista la oportunidad en alg\u00fan momento de contraer matrimonio con una persona extranjera y celebrarse en territorio guatemalteco. Nuestra legislaci\u00f3n, espec\u00edficamente el C\u00f3digo Civil, establece que el matrimonio es una instituci\u00f3n social por la que un hombre y una mujer se unen legalmente, con \u00e1nimo de permanencia y con el fin de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4628,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[761],"tags":[804],"class_list":["post-4627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-derecho-notarial","tag-notarial-y-civil"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Matrimonio en Guatemala Con Extranjero - CONSERVIS ABOGADOS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.conservisabogados.com\/en\/matrimonio-en-guatemala-con-extranjero\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Matrimonio en Guatemala Con Extranjero - CONSERVIS ABOGADOS\" \/>\n<meta property=\"og:description\" content=\"Es posible que exista la oportunidad en alg\u00fan momento de contraer matrimonio con una persona extranjera y celebrarse en territorio guatemalteco. Nuestra legislaci\u00f3n, espec\u00edficamente el C\u00f3digo Civil, establece que el matrimonio es una instituci\u00f3n social por la que un hombre y una mujer se unen legalmente, con \u00e1nimo de permanencia y con el fin de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.conservisabogados.com\/en\/matrimonio-en-guatemala-con-extranjero\/\" \/>\n<meta property=\"og:site_name\" content=\"CONSERVIS ABOGADOS\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-25T16:19:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-02T16:36:44+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.conservisabogados.com\/wp-content\/uploads\/2022\/02\/pexels-jeremy-wong-1043902.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jos\u00e9 Palma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jos\u00e9 Palma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/\"},\"author\":{\"name\":\"Jos\u00e9 Palma\",\"@id\":\"https:\/\/www.conservisabogados.com\/#\/schema\/person\/b70bb6ae5b3b7ff525183d98eb05a1db\"},\"headline\":\"Matrimonio en Guatemala Con Extranjero\",\"datePublished\":\"2022-02-25T16:19:48+00:00\",\"dateModified\":\"2026-03-02T16:36:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/\"},\"wordCount\":610,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.conservisabogados.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.conservisabogados.com\/wp-content\/uploads\/2022\/02\/pexels-jeremy-wong-1043902.jpg\",\"keywords\":[\"notarial y civil\"],\"articleSection\":[\"Notarios y Abogados Civiles en Guatemala\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/\",\"url\":\"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/\",\"name\":\"Matrimonio en Guatemala Con Extranjero - CONSERVIS ABOGADOS\",\"isPartOf\":{\"@id\":\"https:\/\/www.conservisabogados.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.conservisabogados.com\/wp-content\/uploads\/2022\/02\/pexels-jeremy-wong-1043902.jpg\",\"datePublished\":\"2022-02-25T16:19:48+00:00\",\"dateModified\":\"2026-03-02T16:36:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/#primaryimage\",\"url\":\"https:\/\/www.conservisabogados.com\/wp-content\/uploads\/2022\/02\/pexels-jeremy-wong-1043902.jpg\",\"contentUrl\":\"https:\/\/www.conservisabogados.com\/wp-content\/uploads\/2022\/02\/pexels-jeremy-wong-1043902.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.conservisabogados.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Matrimonio en Guatemala Con Extranjero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.conservisabogados.com\/#website\",\"url\":\"https:\/\/www.conservisabogados.com\/\",\"name\":\"CONSERVIS ABOGADOS\",\"description\":\"Bufete de Abogados en Guatemala\",\"publisher\":{\"@id\":\"https:\/\/www.conservisabogados.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.conservisabogados.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.conservisabogados.com\/#organization\",\"name\":\"CONSERVIS ABOGADOS\",\"url\":\"https:\/\/www.conservisabogados.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.conservisabogados.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.conservisabogados.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Conservis-Abogados-Bufete-de-Abogados-en-Guatemala-1.png\",\"contentUrl\":\"https:\/\/www.conservisabogados.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Conservis-Abogados-Bufete-de-Abogados-en-Guatemala-1.png\",\"width\":498,\"height\":500,\"caption\":\"CONSERVIS ABOGADOS\"},\"image\":{\"@id\":\"https:\/\/www.conservisabogados.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.conservisabogados.com\/#\/schema\/person\/b70bb6ae5b3b7ff525183d98eb05a1db\",\"name\":\"Jos\u00e9 Palma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.conservisabogados.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62dd044d2d6f1abf9e1e93aa35390d34200cceba443bc25a1c4b40a0948a473a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62dd044d2d6f1abf9e1e93aa35390d34200cceba443bc25a1c4b40a0948a473a?s=96&d=mm&r=g\",\"caption\":\"Jos\u00e9 Palma\"},\"description\":\"Jos\u00e9 Palma es Abogado Corporativo, Empresario e Inversionista guatemalteco, con m\u00e1s de 12 a\u00f1os de experiencia estructurando y desarrollando negocios en Guatemala. Es cofundador de Conservis Abogados, firma enfocada en asesor\u00eda legal corporativa, sociedades, contratos y protecci\u00f3n patrimonial para empresas. Su enfoque combina estructura legal, visi\u00f3n empresarial y crecimiento sostenible, integrando \u00e1reas clave como asesor\u00eda financiera empresarial, servicios contables en Guatemala y estrategias digitales para generaci\u00f3n de clientes. Conoc\u00e9 m\u00e1s sobre su visi\u00f3n empresarial en josepalmaoficial.com.\",\"sameAs\":[\"https:\/\/josepalmaoficial.com\/\",\"https:\/\/www.instagram.com\/josepalma.oficial\/\",\"https:\/\/www.linkedin.com\/in\/jose-palma\/\",\"https:\/\/youtube.com\/@josepalma.oficial?si=MwwD7tf7fdWTXzQu\"],\"url\":\"https:\/\/www.conservisabogados.com\/en\/author\/jpalma\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Matrimonio en Guatemala Con Extranjero - CONSERVIS ABOGADOS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.conservisabogados.com\/en\/matrimonio-en-guatemala-con-extranjero\/","og_locale":"en_US","og_type":"article","og_title":"Matrimonio en Guatemala Con Extranjero - CONSERVIS ABOGADOS","og_description":"Es posible que exista la oportunidad en alg\u00fan momento de contraer matrimonio con una persona extranjera y celebrarse en territorio guatemalteco. Nuestra legislaci\u00f3n, espec\u00edficamente el C\u00f3digo Civil, establece que el matrimonio es una instituci\u00f3n social por la que un hombre y una mujer se unen legalmente, con \u00e1nimo de permanencia y con el fin de [&hellip;]","og_url":"https:\/\/www.conservisabogados.com\/en\/matrimonio-en-guatemala-con-extranjero\/","og_site_name":"CONSERVIS ABOGADOS","article_published_time":"2022-02-25T16:19:48+00:00","article_modified_time":"2026-03-02T16:36:44+00:00","og_image":[{"width":1280,"height":853,"url":"http:\/\/www.conservisabogados.com\/wp-content\/uploads\/2022\/02\/pexels-jeremy-wong-1043902.jpg","type":"image\/jpeg"}],"author":"Jos\u00e9 Palma","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jos\u00e9 Palma","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/#article","isPartOf":{"@id":"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/"},"author":{"name":"Jos\u00e9 Palma","@id":"https:\/\/www.conservisabogados.com\/#\/schema\/person\/b70bb6ae5b3b7ff525183d98eb05a1db"},"headline":"Matrimonio en Guatemala Con Extranjero","datePublished":"2022-02-25T16:19:48+00:00","dateModified":"2026-03-02T16:36:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/"},"wordCount":610,"commentCount":0,"publisher":{"@id":"https:\/\/www.conservisabogados.com\/#organization"},"image":{"@id":"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conservisabogados.com\/wp-content\/uploads\/2022\/02\/pexels-jeremy-wong-1043902.jpg","keywords":["notarial y civil"],"articleSection":["Notarios y Abogados Civiles en Guatemala"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/","url":"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/","name":"Matrimonio en Guatemala Con Extranjero - CONSERVIS ABOGADOS","isPartOf":{"@id":"https:\/\/www.conservisabogados.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/#primaryimage"},"image":{"@id":"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conservisabogados.com\/wp-content\/uploads\/2022\/02\/pexels-jeremy-wong-1043902.jpg","datePublished":"2022-02-25T16:19:48+00:00","dateModified":"2026-03-02T16:36:44+00:00","breadcrumb":{"@id":"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/#primaryimage","url":"https:\/\/www.conservisabogados.com\/wp-content\/uploads\/2022\/02\/pexels-jeremy-wong-1043902.jpg","contentUrl":"https:\/\/www.conservisabogados.com\/wp-content\/uploads\/2022\/02\/pexels-jeremy-wong-1043902.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/www.conservisabogados.com\/matrimonio-en-guatemala-con-extranjero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.conservisabogados.com\/"},{"@type":"ListItem","position":2,"name":"Matrimonio en Guatemala Con Extranjero"}]},{"@type":"WebSite","@id":"https:\/\/www.conservisabogados.com\/#website","url":"https:\/\/www.conservisabogados.com\/","name":"CONSERVIS ABOGADOS","description":"Law Firm in Guatemala","publisher":{"@id":"https:\/\/www.conservisabogados.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.conservisabogados.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.conservisabogados.com\/#organization","name":"CONSERVIS ABOGADOS","url":"https:\/\/www.conservisabogados.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.conservisabogados.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.conservisabogados.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Conservis-Abogados-Bufete-de-Abogados-en-Guatemala-1.png","contentUrl":"https:\/\/www.conservisabogados.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Conservis-Abogados-Bufete-de-Abogados-en-Guatemala-1.png","width":498,"height":500,"caption":"CONSERVIS ABOGADOS"},"image":{"@id":"https:\/\/www.conservisabogados.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.conservisabogados.com\/#\/schema\/person\/b70bb6ae5b3b7ff525183d98eb05a1db","name":"Jos\u00e9 Palma","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.conservisabogados.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62dd044d2d6f1abf9e1e93aa35390d34200cceba443bc25a1c4b40a0948a473a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62dd044d2d6f1abf9e1e93aa35390d34200cceba443bc25a1c4b40a0948a473a?s=96&d=mm&r=g","caption":"Jos\u00e9 Palma"},"description":"Jos\u00e9 Palma es Abogado Corporativo, Empresario e Inversionista guatemalteco, con m\u00e1s de 12 a\u00f1os de experiencia estructurando y desarrollando negocios en Guatemala. Es cofundador de Conservis Abogados, firma enfocada en asesor\u00eda legal corporativa, sociedades, contratos y protecci\u00f3n patrimonial para empresas. Su enfoque combina estructura legal, visi\u00f3n empresarial y crecimiento sostenible, integrando \u00e1reas clave como asesor\u00eda financiera empresarial, servicios contables en Guatemala y estrategias digitales para generaci\u00f3n de clientes. Conoc\u00e9 m\u00e1s sobre su visi\u00f3n empresarial en josepalmaoficial.com.","sameAs":["https:\/\/josepalmaoficial.com\/","https:\/\/www.instagram.com\/josepalma.oficial\/","https:\/\/www.linkedin.com\/in\/jose-palma\/","https:\/\/youtube.com\/@josepalma.oficial?si=MwwD7tf7fdWTXzQu"],"url":"https:\/\/www.conservisabogados.com\/en\/author\/jpalma\/"}]}},"_links":{"self":[{"href":"https:\/\/www.conservisabogados.com\/en\/wp-json\/wp\/v2\/posts\/4627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.conservisabogados.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conservisabogados.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conservisabogados.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conservisabogados.com\/en\/wp-json\/wp\/v2\/comments?post=4627"}],"version-history":[{"count":1,"href":"https:\/\/www.conservisabogados.com\/en\/wp-json\/wp\/v2\/posts\/4627\/revisions"}],"predecessor-version":[{"id":15909,"href":"https:\/\/www.conservisabogados.com\/en\/wp-json\/wp\/v2\/posts\/4627\/revisions\/15909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conservisabogados.com\/en\/wp-json\/wp\/v2\/media\/4628"}],"wp:attachment":[{"href":"https:\/\/www.conservisabogados.com\/en\/wp-json\/wp\/v2\/media?parent=4627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conservisabogados.com\/en\/wp-json\/wp\/v2\/categories?post=4627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conservisabogados.com\/en\/wp-json\/wp\/v2\/tags?post=4627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}